{"id":99,"date":"2015-03-15T12:26:12","date_gmt":"2015-03-15T11:26:12","guid":{"rendered":"https:\/\/d.th-nuernberg.de\/cast\/?post_type=jetpack-portfolio&#038;p=99"},"modified":"2015-03-15T12:33:27","modified_gmt":"2015-03-15T11:33:27","slug":"nuetzliche-tipps-siebdruck-zu-hause","status":"publish","type":"jetpack-portfolio","link":"https:\/\/d.th-nuernberg.de\/cast\/portfolio\/nuetzliche-tipps-siebdruck-zu-hause\/","title":{"rendered":"N\u00fctzliche Tipps: Siebdruck zu Hause"},"content":{"rendered":"<p>Im 2. Semester suchen wir in Cast nach dem Wesen des Designs.<\/p>\n<p>Wenn die Antwort dann lautet: Siebdruck im Wohnzimmer, entsteht im Laufe der Jahre ein Youtube-Dauerbrenner.<\/p>\n<p>Gedreht im Wohn- und Badezimmer unter leichter Besch\u00e4digung von Licht- und Ton-Equipment. Aber das T-Shirt kann sich sehen lassen.<\/p>\n<div class=\"video-wrapper\"><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe class=\"youtube-player\" width=\"840\" height=\"473\" src=\"https:\/\/www.youtube.com\/embed\/dUeWSuco0SM?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=de-DE&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation allow-popups-to-escape-sandbox\"><\/iframe><\/span><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im 2. Semester suchen wir in Cast nach dem Wesen des Designs. Wenn die Antwort dann lautet: Siebdruck im Wohnzimmer, entsteht im Laufe der Jahre ein Youtube-Dauerbrenner. Gedreht im Wohn- und Badezimmer unter leichter Besch\u00e4digung von Licht- und Ton-Equipment. Aber das T-Shirt kann sich sehen lassen.<\/p>\n","protected":false},"author":2,"featured_media":100,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"jetpack-portfolio-type":[11,4],"jetpack-portfolio-tag":[],"class_list":["post-99","jetpack-portfolio","type-jetpack-portfolio","status-publish","format-standard","has-post-thumbnail","hentry","jetpack-portfolio-type-2-semester-wahrnehmen-analysieren-gestalten","jetpack-portfolio-type-ohmcast","empty-entry-meta","portfolio-entry"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":false,"_links":{"self":[{"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/jetpack-portfolio\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/jetpack-portfolio"}],"about":[{"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/types\/jetpack-portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":0,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/jetpack-portfolio\/99\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/media\/100"}],"wp:attachment":[{"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/media?parent=99"}],"wp:term":[{"taxonomy":"jetpack-portfolio-type","embeddable":true,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/jetpack-portfolio-type?post=99"},{"taxonomy":"jetpack-portfolio-tag","embeddable":true,"href":"https:\/\/d.th-nuernberg.de\/cast\/wp-json\/wp\/v2\/jetpack-portfolio-tag?post=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}